{"id":4530,"date":"2015-04-11T11:19:03","date_gmt":"2015-04-11T11:19:03","guid":{"rendered":"http:\/\/weimarques.es\/blog\/?p=4530"},"modified":"2015-09-02T10:38:39","modified_gmt":"2015-09-02T10:38:39","slug":"si-quieres-seo-a-pasar-todos-por-el-aro-webs-reponsives-a-partir-del-21-de-abril","status":"publish","type":"post","link":"https:\/\/www.weimarques.es\/blog\/si-quieres-seo-a-pasar-todos-por-el-aro-webs-reponsives-a-partir-del-21-de-abril\/","title":{"rendered":"Prepara tu web Responsive para optimizar el SEO"},"content":{"rendered":"\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-top\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;4530&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;top&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;0&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;0&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;2&quot;,&quot;greet&quot;:&quot;&quot;,&quot;legend&quot;:&quot;0\\\/5 - (0 votos)&quot;,&quot;size&quot;:&quot;16&quot;,&quot;title&quot;:&quot;Prepara tu web Responsive para optimizar el SEO&quot;,&quot;width&quot;:&quot;0&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 2px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 2px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 2px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 2px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 2px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 0px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 2px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 2px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 2px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 2px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 2px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 12.8px;\">\n            <span class=\"kksr-muted\"><\/span>\n    <\/div>\n    <\/div>\n<p><strong>\u00bfPorqu\u00e9 a veces nos cuesta tanto cambiar? y una vez cambiamos, \u00bfadaptarnos a ese cambio? <\/strong><\/p>\n<p>El todopoderoso prepotente google, dicta las normas. Te puede parecer mal, imagina que llevas muchos a\u00f1os alimentando tu web, mimando tu SEO, cuidando tu imagen y fidelizando a tus usuarios. Y de repente viene google y te dice que lo est\u00e1s haciendo mal. Pues sinceramente, para mi es una gran noticia. <\/p>\n<p>Te cuento; hace a\u00f1os, antes de las nuevas formas de dise\u00f1o web, ten\u00eda que dise\u00f1ar para diferentes navegadores, pantallas, resoluciones, ordenadores y hacer una programaci\u00f3n que en su d\u00eda era muy variable de uno a otro. \u00bfTe suena intentar hacer alg\u00fan tr\u00e1mite administrativo en una web oficial y que te digan que para usar esa aplicaci\u00f3n de java tienes que entrar desde iexplorer? a mi s\u00ed, y como me reventaba. En aquel entonces, una vez terminada una web a un cliente, \u00e9ste me dijo que se le ve\u00eda mal&#8230; una web que estaba perfecta, muy bien dise\u00f1ada y lo digo de coraz\u00f3n, pero a \u00e9l no se le ve\u00eda bien y fui a investigar a ver porqu\u00e9 era. La estaba viendo desde un iexplorer 6 en un windows xp hace apenas 2 a\u00f1os. Entonces por eso digo que bendito microsoft y bendito google por dar una palmadita a estos que no se aventuran al cambio, a que se estancan y no avanzan y se conforman. HAY QUE SER RESPONSIVE. <\/p>\n<p><strong>\u00bfQu\u00e9 significa responsive?<\/strong><\/p>\n<p>Esta palabreja tan bonita, no quiere decir sino que tu web se va a ver bien en todos los dispositivos del mundo mundial que quieran acceder a ella&#8230; una table de apple, una tablet de lenovo, una TV de samsung, un m\u00f3vil de novia, una blackberry, una xbox, una playstation, el horno de casa, la pantalla de informaci\u00f3n de la estaci\u00f3n de tren, el ipod, el nuevo reloj digital y miles de miles de dispositivos que se te ocurran. Porque al adaptarse a diferentes medidas se navega bien, se utiliza mejor, funciona y se ve bonito !!! <\/p>\n<p><strong>\u00bfPorqu\u00e9 hace \u00e9sto google?<\/strong><\/p>\n<p>Simplemente, estamos en mitad de 2015 !!! p\u00e1rate y piensa como vivimos hoy en d\u00eda. Marti McFly, estamos en el futuro, despierta. El otro d\u00eda tuve una grata experiencia al pedir un taxi por el m\u00f3vil, con la app de mytaxi, estas cosas las estaba dando yo en clase en el posgrado de marketing digital y ecommerce, pero no las hab\u00eda vivido tanto. Pagu\u00e9 con paypal desde el m\u00f3vil al llegar y fu\u00e9 una experiencia maravillosa. Si me lo pones f\u00e1cil te utilizo, me fidelizas, te encuentro y te comparto. Si te quedas atr\u00e1s en una web con mucho contenido y poco \u00fatil me pierdes, y no lo digo porque google te elimine en los buscadores por no ser responsive, lo digo porque el n\u00famero de visitas que tendr\u00e1s en tu web ser\u00e1 mas elevado desde dispositivos m\u00f3viles y al no estar ah\u00ed, no podr\u00e1s conectar con tu nuevo p\u00fablico.<\/p>\n<p>Pero tambi\u00e9n lo hizo microsoft hace poco, cancel\u00f3 el soporte t\u00e9cnico y actualizaciones de Windows xp para darle un empuj\u00f3n a usuarios a que pasen a nuevas versiones y no se estanquen, y por experiencia, les digo que cada d\u00eda veo ordenadores que tienen xp y que siguen las licencias vigentes, algo que me resulta dificil de asimilar.<\/p>\n<p>Si puedes cambiar tu web como est\u00e1, genial. Pero otra opci\u00f3n siempre est\u00e1 en RENOVAR, tener una nueva web, por mucho que te cueste, abre tu mente y arri\u00e9sgate. Por experiencia te digo que a mis clientes, les va genial cuando se ponen en mis manos y me dejan meterme en el proyecto y darle un enfoque radical, creativo y en busca de mejoras. <\/p>\n<p><strong>Si quieres m\u00e1s informaci\u00f3n sobre c\u00f3mo afecta esta noticia de google en tu web, puedes ponerte en contacto conmigo y te cuento un poco m\u00e1s sobre SEO.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"\u00bfPorqu\u00e9 a veces nos cuesta tanto cambiar? y una vez cambiamos, \u00bfadaptarnos a ese cambio? El todopoderoso prepotente&hellip;\n","protected":false},"author":3,"featured_media":4531,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"image","meta":{"footnotes":""},"categories":[9,10,3245,50,3253,3252,2980,3229,16,11,3242,25],"tags":[2453,3302,530,3350,3300,3218,3303,3301,3119,1236],"class_list":["post-4530","post","type-post","status-publish","format-image","has-post-thumbnail","category-curioso","category-design","category-diseno-grafico","category-j-de-hacker","category-mantenimiento","category-marketing-online","category-marketingonline","category-profesionales","category-publicidad","category-tecnologia","category-tienda-online","category-weimarques","tag-disenador-web","tag-dispositivos-moviles","tag-google","tag-madrid","tag-marketingonline","tag-posicionamiento","tag-renovarse","tag-responsive","tag-seo","tag-webdesign","post_format-post-format-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Prepara tu web Responsive para optimizar el SEO &#187; Lisandro Weimarques - blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.weimarques.es\/blog\/si-quieres-seo-a-pasar-todos-por-el-aro-webs-reponsives-a-partir-del-21-de-abril\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prepara tu web Responsive para optimizar el SEO &#187; Lisandro Weimarques - blog\" \/>\n<meta property=\"og:description\" content=\"\u00bfPorqu\u00e9 a veces nos cuesta tanto cambiar? y una vez cambiamos, \u00bfadaptarnos a ese cambio? El todopoderoso prepotente&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.weimarques.es\/blog\/si-quieres-seo-a-pasar-todos-por-el-aro-webs-reponsives-a-partir-del-21-de-abril\/\" \/>\n<meta property=\"og:site_name\" content=\"Lisandro Weimarques - blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/allwelovedesign\" \/>\n<meta property=\"article:published_time\" content=\"2015-04-11T11:19:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-09-02T10:38:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.weimarques.es\/blog\/wp-content\/uploads\/2015\/04\/Captura-de-pantalla-2015-04-10-a-las-11.21.53.png\" \/>\n\t<meta property=\"og:image:width\" content=\"771\" \/>\n\t<meta property=\"og:image:height\" content=\"606\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"weimarques\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@weimarques\" \/>\n<meta name=\"twitter:site\" content=\"@weimarques\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"weimarques\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.weimarques.es\\\/blog\\\/si-quieres-seo-a-pasar-todos-por-el-aro-webs-reponsives-a-partir-del-21-de-abril\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weimarques.es\\\/blog\\\/si-quieres-seo-a-pasar-todos-por-el-aro-webs-reponsives-a-partir-del-21-de-abril\\\/\"},\"author\":{\"name\":\"weimarques\",\"@id\":\"https:\\\/\\\/www.weimarques.es\\\/blog\\\/#\\\/schema\\\/person\\\/9b51895db7f838869b1a9a5043ef9140\"},\"headline\":\"Prepara tu web Responsive para optimizar el SEO\",\"datePublished\":\"2015-04-11T11:19:03+00:00\",\"dateModified\":\"2015-09-02T10:38:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.weimarques.es\\\/blog\\\/si-quieres-seo-a-pasar-todos-por-el-aro-webs-reponsives-a-partir-del-21-de-abril\\\/\"},\"wordCount\":683,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.weimarques.es\\\/blog\\\/si-quieres-seo-a-pasar-todos-por-el-aro-webs-reponsives-a-partir-del-21-de-abril\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weimarques.es\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/Captura-de-pantalla-2015-04-10-a-las-11.21.53.png\",\"keywords\":[\"dise\u00f1ador web\",\"dispositivos m\u00f3viles\",\"google\",\"madrid\",\"marketingonline\",\"posicionamiento\",\"renovarse\",\"responsive\",\"seo\",\"webdesign\"],\"articleSection\":[\"curioso\",\"design\",\"dise\u00f1o grafico\",\"j de hacker\",\"mantenimiento\",\"marketing online\",\"marketingonline\",\"profesionales\",\"publicidad\",\"tecnologia\",\"tienda online\",\"weimarques\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.weimarques.es\\\/blog\\\/si-quieres-seo-a-pasar-todos-por-el-aro-webs-reponsives-a-partir-del-21-de-abril\\\/\",\"url\":\"https:\\\/\\\/www.weimarques.es\\\/blog\\\/si-quieres-seo-a-pasar-todos-por-el-aro-webs-reponsives-a-partir-del-21-de-abril\\\/\",\"name\":\"Prepara tu web Responsive para optimizar el SEO &#187; Lisandro Weimarques - blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weimarques.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.weimarques.es\\\/blog\\\/si-quieres-seo-a-pasar-todos-por-el-aro-webs-reponsives-a-partir-del-21-de-abril\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weimarques.es\\\/blog\\\/si-quieres-seo-a-pasar-todos-por-el-aro-webs-reponsives-a-partir-del-21-de-abril\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weimarques.es\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/Captura-de-pantalla-2015-04-10-a-las-11.21.53.png\",\"datePublished\":\"2015-04-11T11:19:03+00:00\",\"dateModified\":\"2015-09-02T10:38:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.weimarques.es\\\/blog\\\/#\\\/schema\\\/person\\\/9b51895db7f838869b1a9a5043ef9140\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.weimarques.es\\\/blog\\\/si-quieres-seo-a-pasar-todos-por-el-aro-webs-reponsives-a-partir-del-21-de-abril\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.weimarques.es\\\/blog\\\/si-quieres-seo-a-pasar-todos-por-el-aro-webs-reponsives-a-partir-del-21-de-abril\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.weimarques.es\\\/blog\\\/si-quieres-seo-a-pasar-todos-por-el-aro-webs-reponsives-a-partir-del-21-de-abril\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.weimarques.es\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/Captura-de-pantalla-2015-04-10-a-las-11.21.53.png\",\"contentUrl\":\"https:\\\/\\\/www.weimarques.es\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/Captura-de-pantalla-2015-04-10-a-las-11.21.53.png\",\"width\":771,\"height\":606,\"caption\":\"como afecta el cambio de google al seo de mi web\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.weimarques.es\\\/blog\\\/si-quieres-seo-a-pasar-todos-por-el-aro-webs-reponsives-a-partir-del-21-de-abril\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.weimarques.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prepara tu web Responsive para optimizar el SEO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.weimarques.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.weimarques.es\\\/blog\\\/\",\"name\":\"Lisandro Weimarques - blog\",\"description\":\"Freelance Profesional Marketing\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.weimarques.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.weimarques.es\\\/blog\\\/#\\\/schema\\\/person\\\/9b51895db7f838869b1a9a5043ef9140\",\"name\":\"weimarques\",\"url\":\"https:\\\/\\\/www.weimarques.es\\\/blog\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prepara tu web Responsive para optimizar el SEO &#187; Lisandro Weimarques - blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.weimarques.es\/blog\/si-quieres-seo-a-pasar-todos-por-el-aro-webs-reponsives-a-partir-del-21-de-abril\/","og_locale":"es_ES","og_type":"article","og_title":"Prepara tu web Responsive para optimizar el SEO &#187; Lisandro Weimarques - blog","og_description":"\u00bfPorqu\u00e9 a veces nos cuesta tanto cambiar? y una vez cambiamos, \u00bfadaptarnos a ese cambio? El todopoderoso prepotente&hellip;","og_url":"https:\/\/www.weimarques.es\/blog\/si-quieres-seo-a-pasar-todos-por-el-aro-webs-reponsives-a-partir-del-21-de-abril\/","og_site_name":"Lisandro Weimarques - blog","article_publisher":"https:\/\/www.facebook.com\/allwelovedesign","article_published_time":"2015-04-11T11:19:03+00:00","article_modified_time":"2015-09-02T10:38:39+00:00","og_image":[{"width":771,"height":606,"url":"https:\/\/www.weimarques.es\/blog\/wp-content\/uploads\/2015\/04\/Captura-de-pantalla-2015-04-10-a-las-11.21.53.png","type":"image\/png"}],"author":"weimarques","twitter_card":"summary_large_image","twitter_creator":"@weimarques","twitter_site":"@weimarques","twitter_misc":{"Escrito por":"weimarques","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.weimarques.es\/blog\/si-quieres-seo-a-pasar-todos-por-el-aro-webs-reponsives-a-partir-del-21-de-abril\/#article","isPartOf":{"@id":"https:\/\/www.weimarques.es\/blog\/si-quieres-seo-a-pasar-todos-por-el-aro-webs-reponsives-a-partir-del-21-de-abril\/"},"author":{"name":"weimarques","@id":"https:\/\/www.weimarques.es\/blog\/#\/schema\/person\/9b51895db7f838869b1a9a5043ef9140"},"headline":"Prepara tu web Responsive para optimizar el SEO","datePublished":"2015-04-11T11:19:03+00:00","dateModified":"2015-09-02T10:38:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.weimarques.es\/blog\/si-quieres-seo-a-pasar-todos-por-el-aro-webs-reponsives-a-partir-del-21-de-abril\/"},"wordCount":683,"commentCount":0,"image":{"@id":"https:\/\/www.weimarques.es\/blog\/si-quieres-seo-a-pasar-todos-por-el-aro-webs-reponsives-a-partir-del-21-de-abril\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weimarques.es\/blog\/wp-content\/uploads\/2015\/04\/Captura-de-pantalla-2015-04-10-a-las-11.21.53.png","keywords":["dise\u00f1ador web","dispositivos m\u00f3viles","google","madrid","marketingonline","posicionamiento","renovarse","responsive","seo","webdesign"],"articleSection":["curioso","design","dise\u00f1o grafico","j de hacker","mantenimiento","marketing online","marketingonline","profesionales","publicidad","tecnologia","tienda online","weimarques"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.weimarques.es\/blog\/si-quieres-seo-a-pasar-todos-por-el-aro-webs-reponsives-a-partir-del-21-de-abril\/","url":"https:\/\/www.weimarques.es\/blog\/si-quieres-seo-a-pasar-todos-por-el-aro-webs-reponsives-a-partir-del-21-de-abril\/","name":"Prepara tu web Responsive para optimizar el SEO &#187; Lisandro Weimarques - blog","isPartOf":{"@id":"https:\/\/www.weimarques.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.weimarques.es\/blog\/si-quieres-seo-a-pasar-todos-por-el-aro-webs-reponsives-a-partir-del-21-de-abril\/#primaryimage"},"image":{"@id":"https:\/\/www.weimarques.es\/blog\/si-quieres-seo-a-pasar-todos-por-el-aro-webs-reponsives-a-partir-del-21-de-abril\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weimarques.es\/blog\/wp-content\/uploads\/2015\/04\/Captura-de-pantalla-2015-04-10-a-las-11.21.53.png","datePublished":"2015-04-11T11:19:03+00:00","dateModified":"2015-09-02T10:38:39+00:00","author":{"@id":"https:\/\/www.weimarques.es\/blog\/#\/schema\/person\/9b51895db7f838869b1a9a5043ef9140"},"breadcrumb":{"@id":"https:\/\/www.weimarques.es\/blog\/si-quieres-seo-a-pasar-todos-por-el-aro-webs-reponsives-a-partir-del-21-de-abril\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.weimarques.es\/blog\/si-quieres-seo-a-pasar-todos-por-el-aro-webs-reponsives-a-partir-del-21-de-abril\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.weimarques.es\/blog\/si-quieres-seo-a-pasar-todos-por-el-aro-webs-reponsives-a-partir-del-21-de-abril\/#primaryimage","url":"https:\/\/www.weimarques.es\/blog\/wp-content\/uploads\/2015\/04\/Captura-de-pantalla-2015-04-10-a-las-11.21.53.png","contentUrl":"https:\/\/www.weimarques.es\/blog\/wp-content\/uploads\/2015\/04\/Captura-de-pantalla-2015-04-10-a-las-11.21.53.png","width":771,"height":606,"caption":"como afecta el cambio de google al seo de mi web"},{"@type":"BreadcrumbList","@id":"https:\/\/www.weimarques.es\/blog\/si-quieres-seo-a-pasar-todos-por-el-aro-webs-reponsives-a-partir-del-21-de-abril\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.weimarques.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Prepara tu web Responsive para optimizar el SEO"}]},{"@type":"WebSite","@id":"https:\/\/www.weimarques.es\/blog\/#website","url":"https:\/\/www.weimarques.es\/blog\/","name":"Lisandro Weimarques - blog","description":"Freelance Profesional Marketing","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.weimarques.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.weimarques.es\/blog\/#\/schema\/person\/9b51895db7f838869b1a9a5043ef9140","name":"weimarques","url":"https:\/\/www.weimarques.es\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.weimarques.es\/blog\/wp-json\/wp\/v2\/posts\/4530","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weimarques.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weimarques.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weimarques.es\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weimarques.es\/blog\/wp-json\/wp\/v2\/comments?post=4530"}],"version-history":[{"count":0,"href":"https:\/\/www.weimarques.es\/blog\/wp-json\/wp\/v2\/posts\/4530\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.weimarques.es\/blog\/wp-json\/wp\/v2\/media\/4531"}],"wp:attachment":[{"href":"https:\/\/www.weimarques.es\/blog\/wp-json\/wp\/v2\/media?parent=4530"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weimarques.es\/blog\/wp-json\/wp\/v2\/categories?post=4530"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weimarques.es\/blog\/wp-json\/wp\/v2\/tags?post=4530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}