{"id":5680,"date":"2019-05-12T00:15:31","date_gmt":"2019-05-12T00:15:31","guid":{"rendered":"https:\/\/weimarques.es\/blog\/?p=5680"},"modified":"2019-05-12T00:15:33","modified_gmt":"2019-05-12T00:15:33","slug":"lo-unico-que-no-cambia-es-el-mismo-cambio","status":"publish","type":"post","link":"https:\/\/www.weimarques.es\/blog\/lo-unico-que-no-cambia-es-el-mismo-cambio\/","title":{"rendered":"Lo \u00fanico que no cambia, es el mismo cambio"},"content":{"rendered":"\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-top\"\n    data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;5680&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;top&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;2&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;5&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;2&quot;,&quot;greet&quot;:&quot;&quot;,&quot;legend&quot;:&quot;5\\\/5 - (2 votos)&quot;,&quot;size&quot;:&quot;16&quot;,&quot;title&quot;:&quot;Lo \u00fanico que no cambia, es el mismo cambio&quot;,&quot;width&quot;:&quot;89&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 2px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 2px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 2px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 2px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 2px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 89px;\">\n            <div class=\"kksr-star\" style=\"padding-right: 2px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 2px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 2px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 2px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-right: 2px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 16px; height: 16px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 12.8px;\">\n            5\/5 - (2 votos)    <\/div>\n    <\/div>\n\n<p class=\"wp-block-paragraph\">Un carpintero hoy en d\u00eda trabajando con las nuevas m\u00e1quinas, al sentir que acerca la mano peligrosamente la m\u00e1quina se para de forma autom\u00e1tica. En otros casos, se necesitan las dos manos para activar otro tipo de m\u00e1quinas para tener la seguridad de que est\u00e9n ocupadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero no hace mucho tiempo, si a una persona le faltaba alg\u00fan dedo de la mano se supon\u00eda que era carpintero. \u00bfQu\u00e9 ha pasado para conseguir cambiar esta situaci\u00f3n?<\/p>\n\n\n\n<h2 id=\"seguridad-laboral\" class=\"wp-block-heading\">Seguridad Laboral<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Un dise\u00f1ador o programador no deber\u00eda de tener metodolog\u00edas de seguridad laboral, o s\u00ed. Puesto que si no guardas un archivo y el ordenador tiene alg\u00fan problema pierdes todo el trabajo. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">He querido titular el post con referencia al miedo de este sector a cambiar, a actualizar y a mejorar. No es nada dificil crear copias de seguridad, se deben tener cada d\u00eda y a diferentes horas incluso. Crear de forma autom\u00e1tica siempre copias de seguridad y trabajar sin ning\u00fan miedo a poder tirar el movil y todos los equipos de tecnolog\u00eda que tengas por la ventana sin ning\u00fan miedo a perder archivos. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hoy en d\u00eda esto es posible, existen miles de soluciones de cloud (copias en la nube) en donde poder disponer de todos los archivos siempre disponibles en cualquier lugar del planeta. <\/p>\n\n\n\n<h2 id=\"serias-capaz-de-tirar-tu-movil-al-infinito\" class=\"wp-block-heading\">\u00bfSer\u00edas capaz de tirar tu movil al infinito?<\/h2>\n\n\n\n<figure class=\"wp-block-video\"><video height=\"1278\" style=\"aspect-ratio: 720 \/ 1278;\" width=\"720\" controls src=\"https:\/\/weimarques.es\/blog\/wp-content\/uploads\/2019\/05\/2018-04-02-09.57.43.mp4\"><\/video><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Cambiar tu web de servidor es simple. No tienes que darle vueltas, solamente hay que tener buenos conocimientos t\u00e9cnicos para poder montar lo mismo en cualquier servidor. Sin miedo al cambio. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De igual manera ocurre con las actualizaciones de software, cada d\u00eda el ordenador te indica que debes actualizar la versi\u00f3n. Tu web necesita actualizar los sistemas y si lo vas dejando para ma\u00f1ana al final tienes unos archivos obsoletos. Esta semana hemos estado cambiando una web de servidor y al entrar al backend hemos visto que no se actualizaba desde hac\u00eda varios a\u00f1os. Esto no es posible, teniendo copias de seguridad se debe hacer todo sin miedo. \u00bfQu\u00e9 puede pasar? Pues que tengas problemas de incompatibilidad. Por lo que tendr\u00e1s que cargar la anterior versi\u00f3n y tirar de la copia de seguridad. No supone ning\u00fan problema y en menos de 10 minutos tienes toda la web como si no hubieras tocado nada.<\/p>\n\n\n\n<h2 id=\"la-libertad-y-agilidad-de-trabajar-seguro\" class=\"wp-block-heading\">La libertad y agilidad de trabajar seguro<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La diferencia, es que si todos tus sistemas est\u00e1n seguros trabajas sin miedo, trabajas de forma m\u00e1s \u00e1gil y puedes llevar todo al d\u00eda sin ning\u00fan miedo a cometer un error.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Tocando madera, porque hasta ahora no hemos ten\u00eddo ning\u00fan problema por actualizar. Esto, es, mentira.<\/strong><\/p>\n\n\n\n<h2 id=\"problemas-los-hay-por-supuesto\" class=\"wp-block-heading\">Problemas los hay, por supuesto<br><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Este mismo dise\u00f1o de blog est\u00e1 hecho a medida, como cualquiera de las webs de hacemos. Siempre terminamos tocando el c\u00f3digo y mejorando la usabilidad y su aspecto. Pero luego si llega una actualizaci\u00f3n todo esto se pisa y debemos tirar de archivos para dejarlo todo con los mismos cambios. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hemos sufido muchos problemas por actualizaciones, pero es todo parte del cambio. En algunas ocasiones se resuelven ajustando y configurando para que todo encaje, y si no funciona volvemos a la versi\u00f3n anterior antes de actualizar.<\/p>\n\n\n\n<h2 id=\"cada-cuanto-actualizas\" class=\"wp-block-heading\">\u00bfCada cu\u00e1nto actualizas?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Sabes esas actualizaciones que aparecen en wordpress, tanto de la \u00faltima versi\u00f3n como de los diferentes plugins que tienes instalados. Pues bien, esto lo llevamos siempre al d\u00eda en cualquier proyecto. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Hay que darle al bot\u00f3n de actualizar sin miedo. <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y sobre todo en Marketing, se requiere un cambio constante a mejor. No importa lo que has creado, debes mejorar continuamente y crear nuevas versiones<\/p>\n\n\n\n<h2 id=\"conclusion\" class=\"wp-block-heading\">Conclusi\u00f3n<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Continuamente debemos actualizar y no tener miedo a seguir avanzando con la \u00faltima versi\u00f3n. Por otro lado, dejarnos llevar y trabajar constantemente en mejorar y ofrecer siempre mejoras.<\/p>\n","protected":false},"excerpt":{"rendered":"Un carpintero hoy en d\u00eda trabajando con las nuevas m\u00e1quinas, al sentir que acerca la mano peligrosamente la&hellip;\n","protected":false},"author":4,"featured_media":5681,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"image","meta":{"footnotes":""},"categories":[3231,3223,3245,50,1352,3252,2980,11,25],"tags":[3448,3447,3449,3446,737,3228],"class_list":["post-5680","post","type-post","status-publish","format-image","has-post-thumbnail","category-blog","category-corporativas","category-diseno-grafico","category-j-de-hacker","category-madrid","category-marketing-online","category-marketingonline","category-tecnologia","category-weimarques","tag-actualizar-sistemas","tag-actualizar-wordpress","tag-cambiar-servidor","tag-el-cambio","tag-marketing","tag-plan-de-marketing","post_format-post-format-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lo \u00fanico que no cambia, es el mismo cambio &#187; Lisandro Weimarques<\/title>\n<meta name=\"description\" content=\"Hablamos de las actualizaciones de software que deber\u00edas llevar al d\u00eda y de qu\u00e9 forma trabajar en marketing sin miedo con sistemas seguros\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.weimarques.es\/blog\/lo-unico-que-no-cambia-es-el-mismo-cambio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lo \u00fanico que no cambia, es el mismo cambio &#187; Lisandro Weimarques\" \/>\n<meta property=\"og:description\" content=\"Hablamos de las actualizaciones de software que deber\u00edas llevar al d\u00eda y de qu\u00e9 forma trabajar en marketing sin miedo con sistemas seguros\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.weimarques.es\/blog\/lo-unico-que-no-cambia-es-el-mismo-cambio\/\" \/>\n<meta property=\"og:site_name\" content=\"Lisandro Weimarques - blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/allwelovedesign\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-12T00:15:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-05-12T00:15:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.weimarques.es\/blog\/wp-content\/uploads\/2019\/05\/trabajando-sin-miedo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"340\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Lisandro Weimarques\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@weimarques\" \/>\n<meta name=\"twitter:site\" content=\"@weimarques\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lisandro Weimarques\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.weimarques.es\\\/blog\\\/lo-unico-que-no-cambia-es-el-mismo-cambio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weimarques.es\\\/blog\\\/lo-unico-que-no-cambia-es-el-mismo-cambio\\\/\"},\"author\":{\"name\":\"Lisandro Weimarques\",\"@id\":\"https:\\\/\\\/www.weimarques.es\\\/blog\\\/#\\\/schema\\\/person\\\/7699860267ff739e536b8891d7491fd5\"},\"headline\":\"Lo \u00fanico que no cambia, es el mismo cambio\",\"datePublished\":\"2019-05-12T00:15:31+00:00\",\"dateModified\":\"2019-05-12T00:15:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.weimarques.es\\\/blog\\\/lo-unico-que-no-cambia-es-el-mismo-cambio\\\/\"},\"wordCount\":666,\"image\":{\"@id\":\"https:\\\/\\\/www.weimarques.es\\\/blog\\\/lo-unico-que-no-cambia-es-el-mismo-cambio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weimarques.es\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/trabajando-sin-miedo.png\",\"keywords\":[\"actualizar sistemas\",\"actualizar wordpress\",\"cambiar servidor\",\"el cambio\",\"marketing\",\"plan de marketing\"],\"articleSection\":[\"blog\",\"corporativas\",\"dise\u00f1o grafico\",\"j de hacker\",\"madrid\",\"marketing online\",\"marketingonline\",\"tecnologia\",\"weimarques\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.weimarques.es\\\/blog\\\/lo-unico-que-no-cambia-es-el-mismo-cambio\\\/\",\"url\":\"https:\\\/\\\/www.weimarques.es\\\/blog\\\/lo-unico-que-no-cambia-es-el-mismo-cambio\\\/\",\"name\":\"Lo \u00fanico que no cambia, es el mismo cambio &#187; Lisandro Weimarques\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.weimarques.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.weimarques.es\\\/blog\\\/lo-unico-que-no-cambia-es-el-mismo-cambio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.weimarques.es\\\/blog\\\/lo-unico-que-no-cambia-es-el-mismo-cambio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.weimarques.es\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/trabajando-sin-miedo.png\",\"datePublished\":\"2019-05-12T00:15:31+00:00\",\"dateModified\":\"2019-05-12T00:15:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.weimarques.es\\\/blog\\\/#\\\/schema\\\/person\\\/7699860267ff739e536b8891d7491fd5\"},\"description\":\"Hablamos de las actualizaciones de software que deber\u00edas llevar al d\u00eda y de qu\u00e9 forma trabajar en marketing sin miedo con sistemas seguros\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.weimarques.es\\\/blog\\\/lo-unico-que-no-cambia-es-el-mismo-cambio\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.weimarques.es\\\/blog\\\/lo-unico-que-no-cambia-es-el-mismo-cambio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.weimarques.es\\\/blog\\\/lo-unico-que-no-cambia-es-el-mismo-cambio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.weimarques.es\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/trabajando-sin-miedo.png\",\"contentUrl\":\"https:\\\/\\\/www.weimarques.es\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/trabajando-sin-miedo.png\",\"width\":720,\"height\":340},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.weimarques.es\\\/blog\\\/lo-unico-que-no-cambia-es-el-mismo-cambio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.weimarques.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lo \u00fanico que no cambia, es el mismo cambio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.weimarques.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.weimarques.es\\\/blog\\\/\",\"name\":\"Lisandro Weimarques - blog\",\"description\":\"Freelance Profesional Marketing\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.weimarques.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.weimarques.es\\\/blog\\\/#\\\/schema\\\/person\\\/7699860267ff739e536b8891d7491fd5\",\"name\":\"Lisandro Weimarques\",\"sameAs\":[\"http:\\\/\\\/weimarques.es\"],\"url\":\"https:\\\/\\\/www.weimarques.es\\\/blog\\\/author\\\/lisandro-weimarques\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lo \u00fanico que no cambia, es el mismo cambio &#187; Lisandro Weimarques","description":"Hablamos de las actualizaciones de software que deber\u00edas llevar al d\u00eda y de qu\u00e9 forma trabajar en marketing sin miedo con sistemas seguros","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.weimarques.es\/blog\/lo-unico-que-no-cambia-es-el-mismo-cambio\/","og_locale":"es_ES","og_type":"article","og_title":"Lo \u00fanico que no cambia, es el mismo cambio &#187; Lisandro Weimarques","og_description":"Hablamos de las actualizaciones de software que deber\u00edas llevar al d\u00eda y de qu\u00e9 forma trabajar en marketing sin miedo con sistemas seguros","og_url":"https:\/\/www.weimarques.es\/blog\/lo-unico-que-no-cambia-es-el-mismo-cambio\/","og_site_name":"Lisandro Weimarques - blog","article_publisher":"https:\/\/www.facebook.com\/allwelovedesign","article_published_time":"2019-05-12T00:15:31+00:00","article_modified_time":"2019-05-12T00:15:33+00:00","og_image":[{"width":720,"height":340,"url":"https:\/\/www.weimarques.es\/blog\/wp-content\/uploads\/2019\/05\/trabajando-sin-miedo.png","type":"image\/png"}],"author":"Lisandro Weimarques","twitter_card":"summary_large_image","twitter_creator":"@weimarques","twitter_site":"@weimarques","twitter_misc":{"Escrito por":"Lisandro Weimarques","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.weimarques.es\/blog\/lo-unico-que-no-cambia-es-el-mismo-cambio\/#article","isPartOf":{"@id":"https:\/\/www.weimarques.es\/blog\/lo-unico-que-no-cambia-es-el-mismo-cambio\/"},"author":{"name":"Lisandro Weimarques","@id":"https:\/\/www.weimarques.es\/blog\/#\/schema\/person\/7699860267ff739e536b8891d7491fd5"},"headline":"Lo \u00fanico que no cambia, es el mismo cambio","datePublished":"2019-05-12T00:15:31+00:00","dateModified":"2019-05-12T00:15:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.weimarques.es\/blog\/lo-unico-que-no-cambia-es-el-mismo-cambio\/"},"wordCount":666,"image":{"@id":"https:\/\/www.weimarques.es\/blog\/lo-unico-que-no-cambia-es-el-mismo-cambio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weimarques.es\/blog\/wp-content\/uploads\/2019\/05\/trabajando-sin-miedo.png","keywords":["actualizar sistemas","actualizar wordpress","cambiar servidor","el cambio","marketing","plan de marketing"],"articleSection":["blog","corporativas","dise\u00f1o grafico","j de hacker","madrid","marketing online","marketingonline","tecnologia","weimarques"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.weimarques.es\/blog\/lo-unico-que-no-cambia-es-el-mismo-cambio\/","url":"https:\/\/www.weimarques.es\/blog\/lo-unico-que-no-cambia-es-el-mismo-cambio\/","name":"Lo \u00fanico que no cambia, es el mismo cambio &#187; Lisandro Weimarques","isPartOf":{"@id":"https:\/\/www.weimarques.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.weimarques.es\/blog\/lo-unico-que-no-cambia-es-el-mismo-cambio\/#primaryimage"},"image":{"@id":"https:\/\/www.weimarques.es\/blog\/lo-unico-que-no-cambia-es-el-mismo-cambio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.weimarques.es\/blog\/wp-content\/uploads\/2019\/05\/trabajando-sin-miedo.png","datePublished":"2019-05-12T00:15:31+00:00","dateModified":"2019-05-12T00:15:33+00:00","author":{"@id":"https:\/\/www.weimarques.es\/blog\/#\/schema\/person\/7699860267ff739e536b8891d7491fd5"},"description":"Hablamos de las actualizaciones de software que deber\u00edas llevar al d\u00eda y de qu\u00e9 forma trabajar en marketing sin miedo con sistemas seguros","breadcrumb":{"@id":"https:\/\/www.weimarques.es\/blog\/lo-unico-que-no-cambia-es-el-mismo-cambio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.weimarques.es\/blog\/lo-unico-que-no-cambia-es-el-mismo-cambio\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.weimarques.es\/blog\/lo-unico-que-no-cambia-es-el-mismo-cambio\/#primaryimage","url":"https:\/\/www.weimarques.es\/blog\/wp-content\/uploads\/2019\/05\/trabajando-sin-miedo.png","contentUrl":"https:\/\/www.weimarques.es\/blog\/wp-content\/uploads\/2019\/05\/trabajando-sin-miedo.png","width":720,"height":340},{"@type":"BreadcrumbList","@id":"https:\/\/www.weimarques.es\/blog\/lo-unico-que-no-cambia-es-el-mismo-cambio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.weimarques.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Lo \u00fanico que no cambia, es el mismo cambio"}]},{"@type":"WebSite","@id":"https:\/\/www.weimarques.es\/blog\/#website","url":"https:\/\/www.weimarques.es\/blog\/","name":"Lisandro Weimarques - blog","description":"Freelance Profesional Marketing","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.weimarques.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.weimarques.es\/blog\/#\/schema\/person\/7699860267ff739e536b8891d7491fd5","name":"Lisandro Weimarques","sameAs":["http:\/\/weimarques.es"],"url":"https:\/\/www.weimarques.es\/blog\/author\/lisandro-weimarques\/"}]}},"_links":{"self":[{"href":"https:\/\/www.weimarques.es\/blog\/wp-json\/wp\/v2\/posts\/5680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.weimarques.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.weimarques.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.weimarques.es\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.weimarques.es\/blog\/wp-json\/wp\/v2\/comments?post=5680"}],"version-history":[{"count":0,"href":"https:\/\/www.weimarques.es\/blog\/wp-json\/wp\/v2\/posts\/5680\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.weimarques.es\/blog\/wp-json\/wp\/v2\/media\/5681"}],"wp:attachment":[{"href":"https:\/\/www.weimarques.es\/blog\/wp-json\/wp\/v2\/media?parent=5680"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.weimarques.es\/blog\/wp-json\/wp\/v2\/categories?post=5680"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.weimarques.es\/blog\/wp-json\/wp\/v2\/tags?post=5680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}